{"id":8077,"date":"2024-04-22T20:02:47","date_gmt":"2024-04-22T18:02:47","guid":{"rendered":"https:\/\/www.skizunft-basketball.de\/?p=8077"},"modified":"2024-04-23T13:12:35","modified_gmt":"2024-04-23T11:12:35","slug":"die-herren-1-beenden-eine-erfolgreiche-saison-mit-einer-knappen-niederlage-als-aufsteiger-bleiben-die-herren-2-nach-einer-druchwachsenen-saison-in-der-bezirksliga-und-die-herren-3-sowie-die-das-fraue","status":"publish","type":"post","link":"https:\/\/www.skizunft-basketball.de\/index.php\/2024\/04\/22\/die-herren-1-beenden-eine-erfolgreiche-saison-mit-einer-knappen-niederlage-als-aufsteiger-bleiben-die-herren-2-nach-einer-druchwachsenen-saison-in-der-bezirksliga-und-die-herren-3-sowie-die-das-fraue\/","title":{"rendered":"Die Herren 1 beenden eine erfolgreiche Saison mit einer knappen Niederlage. Als Aufsteiger bleiben die Herren 2 nach einer druchwachsenen Saison in der Bezirksliga und die Herren 3 sowie die das Frauenteam stehen im Final Four."},"content":{"rendered":"\n\n\n<p>(KS) Zu ihrem letzten Saisonspiel mussten die <strong>Herrn 1<\/strong> der SZ Giants Kornwestheim beim Schlusslicht der Landesliga, den HAKRO Merlins Crailsheim 3 antreten. Die Merlins, die erst drei Spiele gewonnen hatten, waren gewillt, die Saison mit einem Heimsieg zu beenden. Entsprechend offensiv gingen die Gastgeber in das Spiel. Damit hatten die Giants wohl nicht gerechnet und deshalb auch in der Defensive Probleme die Merlins zu stoppen. Immerhin auch die Giants offensive spielte stark und so endete das erste Viertel unentschieden 25:25. Der Offensivdrang beider Mannschaften setzte sich auch im zweiten Viertel fort. Es ging hin und her mit den erfolgreichen Abschl\u00fcssen. Zum Seitenwechsel lagen dann aber die Merlins knapp mit 50:48 in F\u00fchrung. W\u00e4hrend die Gastgeber auch im dritten Viertel weiterhin Druck machten und zielstrebig zum Korb zogen, geriet aus uner\u00adkl\u00e4rlichen Gr\u00fcnden bei den Kornwestheimer die Offensive ins Stocken. Das nutzten die Merlins und lagen zu Beginn des letzten Viertel mit 74:67 in F\u00fchrung. Den sieben Punkte R\u00fcckstand wollten die Giants in den letzten zehn Minuten dann doch noch drehen. Langsam k\u00e4mpften sich die Kornwestheimer dann auch wieder heran, schafften den Ausgleich und sahen sich auch umgehend wieder mit sieben Punkten im R\u00fcckstand. Die erneute Aufholjagd gelang zwar, war aber nicht vom erw\u00fcnschten Erfolg gekr\u00f6nt. Wenngleich das Schlussviertel mit 19:25 an die Giants ging, am Ende kassierten sie zum Saisonschluss eine unn\u00f6tige, knappe 93:92 Niederlage. In der Schlusstabelle der Landesliga lagen die Kornwestheimer als Aufsteiger mit einer positiven Bilanz von 12 Siegen auf dem vierten Tabellenplatz. Ganz zu Ende ist die Saison f\u00fcr die Giants allerdings noch nicht, denn am kommenden Sonntag steht das Viertelfinale im Bezirkspokal an und da m\u00fcssen die Giants beim Tabellendritten der Landesliga, der TSB Schw\u00e4bisch Gm\u00fcnd antreten.\/<br \/>Es spielten: Ege Irmak Bulundu (8), Andreas D\u00fcrr (6), Manuel Herzog (27), Keith Mounce, Husein Petlaca (8), Leo Piscopello (4), Noah Popescu (23), Tom Schneider (6) und Romans Vavilovs (10).<\/p>\n<p>Zu ihrem letzten Saisonspiel empfingen die <strong>Herren 2<\/strong> in der Hannes-Reiber-Halle den TSV Ingelfingen. Die G\u00e4ste, als Vierter der Bezirks\u00adliga, gingen als Favorit in das Spiel. Allerdings wollten die Giants eine durchwachsen verlaufene Saison mit einem Sieg abschlie\u00dfen. Es lief eigentlich recht gut f\u00fcr die Giants, die bis zur Halbzeit auf Augenh\u00f6he mitspielten, allerdings nach dem ersten Viertel mit 18:19 und beim Seitenwechsel mit 40:41 nur mit einem Punkt im R\u00fcckstand lagen. Nach dem Seitenwechsel verflachte etwas das Spiel. Vor allem die Giants schw\u00e4chelten unterm gegnerischen Korb und lie\u00dfen manche gute Chance liegen. Das verschaffte den G\u00e4sten etwas Luft und sie gingen mit einer 52:58 F\u00fchrung ins Schlussviertel. Wohl wissend, dass sechs Punkte Vorsprung schnell aufzuholen sind, versuchten die Giants das Spiel noch an sich zu Rei\u00dfen. In der Offensive lief es nun auch wieder recht gut. Vor allem die Br\u00fcder Metin Memaj und Samet Memaj dr\u00fcckten dem Angriffsspiel den Stempel auf, wobei Metin Memaj mit 18 Punkten im Schlussviertel gl\u00e4nzte. Leider lie\u00df die Kornwestheimer Defensive aber auch zu viele Chancen der G\u00e4ste zu. Dass das Schlussviertel mit 30:28 an die Giants ging, reichte nicht, um die Saison mit erfolgreich mit einem Sieg abzuschlie\u00dfen. Mit 82:86 musste man sich am Ende geschlagen geben. Wenngleich man in der Schlusstabelle nur auf dem achten Platz landete, als Aufsteiger in die Bezirksliga war der Klassenerhalt geschafft.<br \/>Es spielten: Christoph Genz (5), Adrian Gross (11), Michael H\u00f6nes (10), Dimitrios Mantzalas (), Metin Memaj (28), Samet Memaj (28), Ivan Mijatovic und Erik Mikolajec.<\/p>\n<p>Ebenfalls ihr letztes Heimspiel hatten die <strong>Herren 3<\/strong> gegen die SpVgg M\u00f6hringen. Gegen den Vorletzten der Kreisliga A sollte unbedingt ein Sieg gelingen, um als Tabellenzweiter das Final Four zu erreichen. Und das gelang beeindruckend. Mit einer klaren 101:69 Niederlage schickte man die SpVgg wieder nach Hause. Zu Beginn des Spiels lie\u00df man die G\u00e4ste allerdings noch flei\u00dfig mitspielen, die Akzente setzte allerdings die Kornwestheimer Offensive. So ging das erste Viertel mit 29:20 an die Giants. Im zweiten Viertel stand die Kornwestheimer Defensive deutlich besser, daf\u00fcr klappte es in der Offensiver nicht mehr so gut. Trotzdem die Giants bestimmten das Spiel und lagen zur Halbzeit mit 46:33 in F\u00fchrung. Im dritten Viertel waren dann wieder die Kornwestheimer Offensivkr\u00e4fte Herr im Haus und markierten Punkt f\u00fcr Punkt. Mit einer klaren 71:52 F\u00fchrung ging es ins Schlussviertel und da drehten die Giants noch einmal richtig auf, markierten weitere 30 Punkte und knackten auch noch die Hundertermarke. Damit haben die Giants ihr Ziel erreicht, stehen in der Schlusstabelle auf dem zweiten Platz und sind f\u00fcr das Final Four qualifiziert. <br \/>Es spielten: Aurimas Cerniauskas (6), Zukas Edmundas (3), Eimantas \u00a0Keleris (12), Tomas Kerbelis (15), Kazilas Kipras (25), Jovaldas Paliksa (9),\u00a0 Edvinas Raguotis, Dominykas Savicius (5), Andrijauskas Tadas (2),\u00a0 Modestas Tumonis (4), Tautvydas Urbsaitis (14) und Juozas Vasiliauskis (6).<\/p>\n<p>Auch f\u00fcr das<strong> Frauenteam <\/strong>der Kornwestheimer Giants stand das letzte Saisonspiel an. Sie empfingen die Aalener Sportallianz. Gegen das Schlusslicht der Bezirksliga waren die Giants-Damen deutlich \u00fcberlegen. Zwar verlief das erste Viertel noch zaghaft, aber man lag mit 10:6 in F\u00fchrung. Im zweiten Viertel steigerten sich die Giants. Die Defensive hielt die Aalener in Schach und im Angriff punktete man nun oft erfolgreich. Mit einer 29:16 F\u00fchrung ging man in die Halbzeitpause. Auch nach dem Seitenwechsel bestimmten die Kornwestheimerinnen weiter das Spielgeschehen und bauten im dritten Viertel ihre F\u00fchrung auf 51:31 aus. Da die G\u00e4ste auch im Schlussviertel nichts entgegen\u00adsetzen konnten, feierten die Giants einen deutlichen 68:43 Heimsieg. In der Schlusstabelle belegen die Kornwestheimerinnen den zweiten Platz und haben sich nun f\u00fcr das Final Four qualifiziert.<br \/>Es spielten: Leyla Abdul Hamid (16), Aileen Aynacioglu (6), Dilara Aynacioglu (8), Irini Kiriaki Braun (6), Annabel Frimpong, Viktoria Giljanovic (8), Cecilia Gvozdic (4), Amelie Kienast (4), Lorena Lantella (4), Miray Poyraz (2) und Leonita Sadiku (10).<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00dcberraschungssieg der U 18\/1 gegen BBU 01 Ulm!<\/strong><br \/><strong>Die U 16\/1 feiert gleich zwei Siege in der Jugend Oberliga und auch die weibliche U 14\/1 ist erfolgreich<\/strong><\/p>\n<p>Zu einem \u00fcberraschend deutlichen Heimsieg kam die <strong>U 18\/1<\/strong> gegen die BBU 01 Ulm. Nachdem der Tabellenzweite der Jugend Oberliga (Platzierungsrunde Ost) die Giants zu Hause mit 86:44 eine deutliche Niederlage verpasste, drehten die Giants zu Hause den Spie\u00df um. Dass die Giants so stark aufspielten, damit hatten die Ulmer offenbar nicht gerechnet. Von Beginn an waren die Kornwestheimer Offensivkr\u00e4fte hellwach und von den Ulmern nicht zu stoppen. Nach einem 16:0-Lauf im ersten Viertel lagen die Giants nach den ersten zehn Minuten mit 30.16 deutlich in F\u00fchrung. Zwar wurde im zweiten Viertel die Ulmer Offensive nun auch deutlich st\u00e4rker, aber die Giants waren immer noch Herr des Geschehens. So ging das zweite Viertel mit 29.24 erneut an die Giants, die so mit einer 59:40 F\u00fchrung in das dritte Viertel gingen. Das offensive Spiel der Giants setzte sich auch nach dem Seitenwechsel fort. Zudem bekamen die Kornwestheimer Defensivkr\u00e4fte die Ulmer wieder besser in Griff. W\u00e4hrend Ulm kaum etwas entgegenzusetzten hatte, zogen die Giants kontinuierlich auf und davon. Nach einer deutlichen 84:56 F\u00fchrung am Ende des dritten Viertel, hatte Ulm keinen Willen mehr das Spiel zu drehen. Daf\u00fcr bedankten sich die Giants, bei denen sich am Ende alle Spieler in die Trefferliste eingetragen hatten und sie knackten im Schlussviertel noch die Hundertermarke. Mit 106:77 stand ein in dieser H\u00f6he nicht erwarteter klarer Heimsieg zu Buche. Die Giants bleiben trotz des Erfolgs auf dem f\u00fcnften Tabellenplatz.<br \/>Es spielten: Luka Dokoza (2), Thomas Engelhard (2), Henning L\u00fctters (2), Husein Petlaca (25), Noah Popescu (23), Luca Reichert (2), Taulant Sallahi (8), Finn Thom (4), Kevin Tobias (30) und Dennis Welther (7).<\/p>\n<p>Ein Nachholspiel in der Jugend-Oberliga (Platzierungsrunde Nord) hatte die <strong>U 16\/1<\/strong> der Giants. Sie empfingen den Tabellenletzten, die BG Karlsbad. Die Karlsbader waren spielerisch st\u00e4rker, als dies der Tabellenplatz aussagt. Dem entsprechend mussten die Giants k\u00e4mpfen um am Ende das enge Spiel mit 64:59 zu gewinnen. Nachdem die Giants schnell mit 9:0 in F\u00fchrung lagen, fanden nach und nach auch die G\u00e4ste zu ihrem Spiel und waren ein gleichwertiger Gegner. So endete das erste Viertel ausgeglichen mit 18:18. Auch im zweiten Viertel hielten die G\u00e4ste dagegen, doch den Giants gelang es sich etwas Luft zu verschaffen und lagen zur Halbzeit mit 32:27 in F\u00fchrung. Die knappe F\u00fchrung konnten die Giants auch im dritten Viertel verteidigen und gingen mit einer 48:44 F\u00fchrung ins Schlussviertel. Nachdem man sich mit einem 8:0 Lauf zun\u00e4chst auf 58:50 absetzten konnte, kamen die Karlsbader mit zwei Dreier in Folge wieder heran, konnten aber den Sieg der Giants dann doch nicht verhindern.<br \/>Am Wochenende folgte dann ein weiteres Heimspiel gegen den VfL Waiblingen. Und auch gegen den Tabellendritten gingen die Giants als Sieger vom Spielfeld. Es war allerdings ein harter Kampf, denn die G\u00e4ste spielten auf Augenh\u00f6he mit und waren zeitweise das etwas st\u00e4rkere Team. Die Giants verstanden es allerdings, dran zu bleiben, so dass Waiblingen nicht davonziehen konnte. Nach dem ersten Viertel lagen die Giants noch mit 14:17 zur\u00fcck, doch bei Halbzeit war der Spielstand mit 28:28 ausgeglichen, weil die Kornwestheimer Defensive im zweiten Viertel nun kaum noch Treffer der G\u00e4ste zulie\u00df. Nach dem Seitenwechsel gelang es den Giants zun\u00e4chst einen acht Punkte Vorsprung heraus zuspielen, ehe der VfL zum Ende des dritten Viertels den Vorsprung auf 47:43 verk\u00fcrzte. Im recht offensiven letzten Viertel schenkten sich beide Teams nichts und waren immer wieder erfolgreich unterm gegnerischen Korb. Mit 20:20 endeten die letzten zehn Minuten und das war dann auch der verdiente 67:63 Heimsieg. Trotz der beiden Siege bleiben die Giants auf dem vierten Tabellenplatz der Jugend-Oberliga (Platzierungs\u00adrunde Nord).<br \/>Es spielten: Hannes Empacher, Jonas Kienast (2\/-), Petar Kljajic (-\/2), Semin Mesanovic, Valentin M\u00f6ssinger (21\/13), Marko Pejkic (14\/10), Stefan Rablou (14\/12), Taulant Sallahi (6\/10), Marko Tomic (-\/4), Julius Waibel (-\/11) und Oliver Zeitz (7\/5).<\/p>\n<p>Zu ihrem letzten Spiel in der Landesliga musste die <strong>U 16\/2<\/strong> bei REWE Aupperle Fellbach antreten. Im Prinzip hatte das Spiel nur noch statistischen Wert, denn beide Teams hatten weder Aussicht auf die Teilnahme am Final Four, noch etwas mit dem Abstieg zu tun. Trotzdem spielten beide Teams beherzt und wollten zum Schluss noch einmal einen Sieg. Den feierten dann allerdings die Kornwestheimer, die denkbar knapp mit 67:68 gewannen. Damit beenden die Giants die Saison auf dem vierten Tabellenplatz.<br \/>Es spielten: Marko Aleksic, Tom Beckert,\u00a0 Maximilian Behn,\u00a0 Roan Filip Gec, Simon Hoinle, Alexandros Katsaounis, Jayden Kenserski, Luis Kretz, Leo von Tietzen, Emanuel Wantsis und Davide Zambuto.<\/p>\n<p>Zum Saisonabschluss in der Bezirksliga musste die <strong>weibliche U 14<\/strong>\u00a0 beim Schluss\u00adlicht, SG Schorndorf antreten. Und das Spiel wurde zu einer klaren Sache f\u00fcr die Giants. Nach einer 4:10 F\u00fchrung nach zehn Minuten zogen die Kornwestheimer M\u00e4dchen im zweiten Viertel gleich mit einem 14:0-Lauf auf und davon und lagen zur Halbzeit deutlich mi 8:28 in F\u00fchrung. Da die Gastgeberinnen auch nach dem Seitenwechsel kaum Paroli bieten konnten, erh\u00f6hten die Giants im dritten Viertel Punkt f\u00fcr Punkt ihre F\u00fchrung und gingen mit 16:45 in das Schlussviertel. In den letzten zehn Minuten, rissen dann beider Teams keine B\u00e4ume mehr raus, und das Spiel pl\u00e4tscherte dahin. Am Ende konnten die Giants M\u00e4dchen dann einen klaren 26:51 Ausw\u00e4rtssieg. Bejubelten. In der Tabelle liegen die Kornwestheimerinnen nun auf dem f\u00fcnften Platz.<br \/>Es spielten: Leni Buchen (9), Sarah Cseszka (2), Layla Pearl Kenserski, Greta Mantel (8),\u00a0 Belinay Poyraz (25), Anna Schoch (6), Erika Obianuju Udeh (4) und Ljubica Zivkovic (2).<\/p>\n<p>Auch die <strong>U 12\/2<\/strong> hatte zum Saisonabschluss noch einen Doppelspieltag. Zun\u00e4chst ging es zur TSG Heilbronn und da waren die Giants chancenlos. Mit 81:55 kassierten die jungen Giants eine klare Niederlage.<br \/>Am Sonntag war man dann bei der BSG Vaihingen-Sachsenheim zu Gast. Gegen Das Schlusslicht der Bezirksliga durften die jungen Giants dann jubeln. Mit einem deutlichen 53:95 besiegte man die Gastgeber. Durch diesen Sieg zogen die Giants an der BG Remseck vorbei und kletterten auf den f\u00fcnften Tabellenplatz.<br \/>Es spielten: Nusret Akpunar, Selim Balaban, Ali Serkan Bing\u00f6l, Elias Googe, Muhammed Ali Kaya, Enes Kilbas, Ahmet Ediz Sava, und Georgios Dimitrios Tsiaras.<\/p>\n<p>\u00a0<\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>(KS) Zu ihrem letzten Saisonspiel mussten die Herrn 1 der SZ Giants Kornwestheim beim Schlusslicht der Landesliga, den HAKRO Merlins Crailsheim 3 antreten. Die Merlins, die erst drei Spiele gewonnen &#8230;<\/p>\n","protected":false},"author":6,"featured_media":7484,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,23],"tags":[],"class_list":["post-8077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-spielberichte"],"_links":{"self":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/8077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/comments?post=8077"}],"version-history":[{"count":1,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/8077\/revisions"}],"predecessor-version":[{"id":8078,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/8077\/revisions\/8078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/media\/7484"}],"wp:attachment":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/media?parent=8077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/categories?post=8077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/tags?post=8077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}