{"id":9086,"date":"2025-03-17T16:11:07","date_gmt":"2025-03-17T15:11:07","guid":{"rendered":"https:\/\/www.skizunft-basketball.de\/?p=9086"},"modified":"2025-03-17T16:11:07","modified_gmt":"2025-03-17T15:11:07","slug":"die-herren-1-koennen-nicht-mehr-gewinnen-haben-aber-trotzdem-den-klassenerhalt-geschafft","status":"publish","type":"post","link":"https:\/\/www.skizunft-basketball.de\/index.php\/2025\/03\/17\/die-herren-1-koennen-nicht-mehr-gewinnen-haben-aber-trotzdem-den-klassenerhalt-geschafft\/","title":{"rendered":"Die Herren 1 k\u00f6nnen nicht mehr gewinnen, haben aber trotzdem den Klassenerhalt geschafft."},"content":{"rendered":"\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Nach zuletzt drei verlorenen Spielen und dem Abrutschen auf den zehnten Tabellenplatz der Landesliga, sollten im Heimspiel der <strong>Herren 1 <\/strong>der SZ Giants gegen den TV Obert\u00fcrkheim mal wieder beide Punkte in Kornwestheim bleiben. Die Giants hatten aber die Rechnung ohne den Wirt gemacht und kassierten erneut eine bittere 53:75 Niederlage. Von Beginn an fanden die Giants nicht zu ihrem Spiel. Sowohl die Defensive, wie auch die Offensive zeigte Schw\u00e4chen. Das erste Viertel ging zwar noch einigerma\u00dfen glimpflich aus und man lag nur mit 10:16 im R\u00fcckstand, doch im zweiten Viertel markierten die G\u00e4ste Punkt f\u00fcr Punkt, die mit einem 18:0-Lauf in das Viertel starteten und bis zur Halbzeit auf 20:42 davonzogen. Nach dem Seitenwechsel kamen die Kornwestheimer Angreifer dann etwas besser ins Spiel, da aber die Defensive nach wie vor zu viele L\u00fccken offenbarte ging auch das dritte Viertel klar mit 17:24 an die Obertr\u00fcrkheimer, die somit mit einer 37:66 F\u00fchrung in das Schlussviertel gingen. Die letzten zehn Minuten waren f\u00fcr die G\u00e4ste dann nur noch reine Formsache. Trotz der erneuten Niederlage bleiben die Giants auf dem zehnten Tabellenplatz\u00a0\u00a0 und sie haben den Klassenerhalt geschafft. Bei nur noch einem ausstehenden Spiel k\u00f6nnen sie weder von Vorletzten, noch vom Letzten der Tabelle vom zehnten Platz verdr\u00e4ngt werden.<br \/>Es spielten: Timur Atici (6), Frederik Bergner (2), Stephan B\u00f6ttcher (9), Amadou Cisse (8), Thomas Engelhard, Samuel Kurr (11),Andreas Laing (2), Joel Parsche (5), Shinnosuke Sato (2) und Patrick Zirn (8).<\/p>\n<p><strong>Zweifacher Erfolg der Herren 3<\/strong><\/p>\n<p>Gleich zwei Spiele mussten die <strong>Herren 3<\/strong> der Giants an diesem Wochenende bestreiten. Auf dem Papier waren die Giants bei beiden Spielen klarer Favorit. Zuerst war der Tabellenvorletzte, der TSV Schwaikheim zu Gast in der Hannes- Reiber-Halle. Das Spiel kam nur schleppend in Gang. Beide Teams waren bei den Abschl\u00fcssen unterm Korb v\u00f6llig von der Rolle. Gerade mal acht Punkte gingen auf das Konto der Giants und sogar nur sechs an die G\u00e4ste. Im zweiten Viertel wurde das Spiel der Giants deutlich besser. Nach und nach bauten sie ihre F\u00fchrung aus und lagen zur Halbzeit mit 25:16 vorne. In der zweiten Halbzeit machten es die Giants dann allerdings spannend und \u00fcberlie\u00dfen im dritten Viertel das Spiel den G\u00e4sten. Die machten Punkt f\u00fcr Punkt gut und kamen bis auf drei Punkte heran. So lagen die Giants nur noch mit 38:35 in F\u00fchrung. Gleich zu Beginn des Schlussviertels gelang es den Giants ihre F\u00fchrung wieder auf zehn Punkte auszubauen. Die Giants lie\u00dfen sich nun nicht mehr die Butter vom Brot nehmen und gewannen mit 57:51.<\/p>\n<p>Am n\u00e4chsten Tag ging es dann zum Schlusslicht der Bezirksliga 2, den Steinenbronn Beasts. Und da machten es die Giants spannend, denn das Schlusslicht durfte munter mitspielen. Zun\u00e4chst waren es die Giants die besser ins Spiel fanden und die Gastgeber auf Distanz halten konnten. Mit 16:22 ging das erste Viertel an die Giants. Anstelle so weiterzuspielen, \u00fcberlie\u00dfen die Giants das zweite Viertel mehr oder weniger den Gastgebern. Die nutzten ihre Chancen, machten den R\u00fcckstand wett und lagen zur Halbzeit dann mit 36:34 in F\u00fchrung. Die Beasts witterten die Chance auf einen Sieg. So entwickelte sich im dritten Viertel ein Spiel auf Augenh\u00f6he. In den Schlusssekunden des dritten Viertels gelang es den Giants dann wieder mit 51:53 in F\u00fchrung zu gehen. Die Gastgeber wollten aber weiterhin den Heimsieg. So wechselte im Schlussviertel die F\u00fchrung hin und her. Erst in den letzten zwei Spielminuten gelang es den Giants dann doch noch das Spiel f\u00fcr sich zu entscheiden. Mit einem knappen 66:70 Ausw\u00e4rtssieg war dann das doppelte Spielwochenenden mit vier Punkte perfekt. In der Tabelle liegen die Giants auf dem sechsten Platz und haben bei noch zwei ausstehenden Spielen mit dem Abstieg nichts zu tun.<\/p>\n<p>Es spielten: Dominykas Barauskas, \u0160er\u0161enis Deividas (23\/33), Eilmantas Keleris (8\/8), Tomas Kerbelis (-\/4), Kazilas Kipras (10\/6), Andrius Kudarauskas (1\/-), Martinkus Merunas (2\/7), Jovaldas Paliksa (6\/6), Dominykas Savicius (6\/-), Andrijauskas Tadas, Tautvydas Urbsaitis (1\/2) und Juozas Vasiliauskis (-\/4).<\/p>\n<p>\u00a0<\/p>\n<p><strong>Die U 18\/1 kann in der Jugend-Oberliga doch noch gewinnen und die weibliche U 14 \u00fcbernimmt wieder die Tabellenf\u00fchrung!<\/strong><\/p>\n<p>F\u00fcr die <strong>U 18\/1<\/strong> der SZ Giants Kornwestheim stand am Wochenende in der Jugend Oberliga Ost das R\u00fcckspiel bei der BBU 01 Ulm an. Nachdem man vor zwei Wochen zu Hause klar mit 47:74 unter ging, wollte man eine weitere klare Niederlage vermeiden. Aber es kam noch besser, denn am Ende verbuchten die Giants mit einem 72:81 Ausw\u00e4rtssieg beide Punkt auf ihrem Konto. Vielleicht hatten die Ulmer nach ihrem klaren Sieg vor zwei Wochen den Kampfgeist der Giants untersch\u00e4tzt, denn die Spielten munter mit und hielten die Partie in den ersten beiden Vierteln offen. Nach einer 19:20 F\u00fchrung nach den ersten zehn Minuten gingen die Giants mit einer 39:42 Halbzeitf\u00fchrung in die Pause. Das dritte Viertel begann fulminant aus Sicht der Giants die drei Dreier markierten und einen 10:0-Lauf hinlegten. Die Ulmer hatten in diesem Viertel nicht viel dagegen zu setzten, zumal auch die Defensive der Giants gutstand und die Ulmer Angreifer in Schach hielt. So ging das dritte Viertel mit 11:20 klar an die Giants die nun mit 12 Punkten, 50:62 in F\u00fchrung lagen. Das Schlussviertel wurde dann zu einem offenen Schlagabtausch, weil Ulm versuchte die Niederlage abzuwenden. Aber die Giants hatten die passende Antwort und hielten letztendlich Ulm auf Distanz.<br \/>Es spielten: Frederik Berger (21), Sven Aurel Delic, Thomas Engelhard (10), Kilian Goldstein (15), Fabian Harre (7), Gino Kouadio (2), Deniz Lepke (2), Luca Reichert, Shinnosuke Sato (2) und Marvin Selmani (12).<\/p>\n<p>Die <strong>U 18\/2<\/strong> als Tabellenf\u00fchrer der Landesliga musste beim Verfolger, den HAKRO Merlins Crailsheim antreten. Es wurde das versprochene Spitzenspiel, den beide Teams schenkten sich nichts. Die Merlins gingen im ersten Viertel mit 28:23 in F\u00fchrung, doch zur Halbzeit hatten die Giants mit 44:47 die Nase vorne. Im dritten Viertel waren es zun\u00e4chst die Merlins, die sich mehr Vorteile herausspielten und nach sechs Spielminuten mit 10 Punkten in F\u00fchrung lagen. Dann aber kam die Zeit der Giants, die einen 11:0-Lauf hinlegten und somit wenn auch knapp, weiterhin mit 71:73 in F\u00fchrung lagen. Die F\u00fchrung hielt allerdings nicht lange und mit vier Dreiern innerhalb k\u00fcrzester Zeit, zogen die Merlins auf 91:75 davon. Von diesem Schock erholten sich die Giants nicht mehr und mussten sich nach langem gro\u00dfem Kampf mit 105:91 dann doch noch deutlich geschlagen geben. Der 14 Punktesieg der Merlins reichte allerdings nicht, die Giants vom ersten Platz zu verdr\u00e4ngen. Beide Teams sind zwar punktgleich, doch die Giants hatten das Hinspiel mit 26 Punkten unterschied gewonnen und liegen somit im direkten Vergleich vorne.<br \/>Es spielten: Luke Conrad (6), Sam Conrad (10), Roan Filip Gec, Jaydan Kenserski, Henning L\u00fctters (22), Luan Mader (), Konstantin Selcho (2), Julius Waibel (24) und Oliver Zeitz (1).<\/p>\n<p>Nachdem es bei den Young Tiger T\u00fcbingen in der Jugend Oberliga S\u00fcd auch nicht so gut l\u00e4uft, wollte die <strong>U 14\/1<\/strong> der Giants den Tigers ein Bein stellen und m\u00f6glichst beide Punkte mit nach Hause nehmen. Daraus wurde allerdings nichts. Die Tigers pr\u00e4sentierten sich als zu stark. Nur in den ersten zehn Minuten konnten die Giants mithalten und lagen nur mit 21:19 im R\u00fcckstand. Danach dominierten nur noch die Tigers, die zur Halbzeit mit 45:34 in F\u00fchrung lagen. Auch nach dem Seitenwechsel hatten die Giants nicht viel entgegenzusetzen. Die Tigers zogen auf 77:43 davon und schlugen am Ende die Giants deutlich mit 90:57. Trotz der Niederlage bleiben die Giants auf dem sechsten Tabellenplatz..<br \/>Es spielten: Benil Asani (2), Justus Baumgartner (4), Kerem Cerit (8), Bora Jusofoski (2), Angelos Katsaounis (6), Naim Elias Kaya (1), Majd Mesanovic (10), Gerogieje Lav Popovic (1), Kurtay Poyratz (5), Kian Retzlaf (6), \u00a0und Dario Secen (12).<\/p>\n<p>Der Tabellenf\u00fchrer der Kreisliga A2, die BG Tamm\/Bietigheim erwies sich f\u00fcr die <strong>U 14\/2<\/strong> der Giants als ein zu starker Brocken. Die BG besiegten die Giants mit 48:72. Dabei starten die Giants stark und \u00fcberraschenten die BG. Die lag n\u00e4mlich nach den ersten zehn Minuten mi 24:10 im R\u00fcckstand. Und auch im zweite Viertel spielten die die Giants forsch weiter und lagen zur Halbzeit immer noch mit 35:26 in F\u00fchrung. Im dritten Viertel wendete sich das Blatt. Der Tabellenf\u00fchrer machte ernst. Die Giants bekamen nun gegen die stark spielenden G\u00e4ste kaum noch Chancen zu einem erfolgreichen Abschluss, w\u00e4hrend die BG Punkt f\u00fcr Punkt erzielte und das Viertel mit 5:24 gewann. Damit lag die BG mit 40:50 in F\u00fchrung und die baute die BG bis zum Ende zu einem 48:72 Sieg aus. Die Niederlage tut den Giants nicht weh. Sie bleiben auf dem vierten Tabellenplatz.<br \/>Es spielten: Selim Balaban, Renas Celik (4), Elias Googe (1), Yevhen Konin (3), Emanuel Lajk (14), Lukas Mayer, Dominik Dieter Merkle (4), Vincent Meyer und Georios Dimitrios Tsiaras (22).<\/p>\n<p>Bisher l\u00e4uft es f\u00fcr die <strong>weibliche U 14<\/strong> der Giants recht gut in der Bezirksliga. Gegen den Tabellenletzten der Bezirksliga feierten die Kornwestheimerinnen ihren f\u00fcnften Sieg und eroberten dadurch die Tabellenf\u00fchrung zur\u00fcck. Die G\u00e4ste hatten nicht viel den stark spielenden Giants entgegenzusetzten. Die lagen nach zehn Minuten bereits mit 22:6 in F\u00fchrung. Munter spielten die Giants weiter und erh\u00f6hten bis zur Halbzeit ihre F\u00fchrung auf 38:13. Da die BG M\u00e4dchen auch in der zweiten Halbzeit nicht viel entgegen setzten, durfte die Topscorerin der Giants, Dalia Bsul, weiter ihr Trefferkonto auf 25 Punkte erh\u00f6hen. \u00dcber 53:21 kamen die Giants M\u00e4dchen zu einem ungef\u00e4hrdeten 63:29 Heimsieg. \u00a0<br \/>Es spielten: Dalia Bsul (25), Leni Buchen (6), Sarah Cseszka (6), Lena Kaiser,Layla Pearl Kenserski, Greta Mantel (6), Belinav Poyraz (6), Anna Schoch (2), Erika Obianuju Udeh (8) und Ljubica Zivkovic (4).<\/p>\n<p>Gleich zwei Spiele musste die <strong>U 12\/1<\/strong> am Wochenende bestreiten. Zuerst musste man bei den Porsche BBA Ludwigsburg (schwarz) antreten. Nachdem die Ludwigsburger schon im Hinspiel das Nachsehen hatten, nahmen die Giants auch aus Ludwigsburg mit einem 73:88 Sieg beide Punkte mit nach Hause. Schon zur Halbzeit sah es f\u00fcr die Giants nach einem klaren Sieg aus, denn da lagen sie bereits mit 40:54 in F\u00fchrung.\u00a0 \u00a0\u00a0<br \/>Am n\u00e4chsten Tag waren dann die PKF Titans Stuttgart zu Gast. Und auch die Titanen aus Stuttgart hatten das Nachsehen. Die Stuttgarter G\u00e4ste mussten ebenfalls der F\u00fchrung der Giants st\u00e4ndig hinterherlaufen. Mit einer 77:67 Niederlage wurden sie wieder nach Hause geschickt. Nach ihrem achten Sieg belegen die Giants in der Landesliga den zweiten Tabellenplatz.<br \/>Es spielten: Ian Arbinger, Paul Enderle, Timon Feege, Todor Gajic, Marko Gregovic, Jannis Haustein, Malik Ilay Kaya, und Matija Moldovan.<\/p>\n<p>\u00a0<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Nach zuletzt drei verlorenen Spielen und dem Abrutschen auf den zehnten Tabellenplatz der Landesliga, sollten im Heimspiel der Herren 1 der SZ Giants gegen den TV Obert\u00fcrkheim mal &#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9086","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/9086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/comments?post=9086"}],"version-history":[{"count":1,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/9086\/revisions"}],"predecessor-version":[{"id":9087,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/9086\/revisions\/9087"}],"wp:attachment":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/media?parent=9086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/categories?post=9086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/tags?post=9086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}