{"id":9238,"date":"2025-05-19T15:25:27","date_gmt":"2025-05-19T13:25:27","guid":{"rendered":"https:\/\/www.skizunft-basketball.de\/?p=9238"},"modified":"2025-07-10T14:51:02","modified_gmt":"2025-07-10T12:51:02","slug":"die-u-18-2-feiert-ihren-meistertitel-in-der-landesliga-in-der-bezirksliga-wird-die-weibliche-u-14-vierter","status":"publish","type":"post","link":"https:\/\/www.skizunft-basketball.de\/index.php\/2025\/05\/19\/die-u-18-2-feiert-ihren-meistertitel-in-der-landesliga-in-der-bezirksliga-wird-die-weibliche-u-14-vierter\/","title":{"rendered":"Die U 18\/2 feiert ihren Meistertitel in der Landesliga. In der Bezirksliga wird die weibliche U 14 vierter."},"content":{"rendered":"\n<p>In der<strong> Landesliga der U 18 Teams<\/strong> hatten sich die ersten vier, also die HAKRO Merlins Crailsheim, <strong>SZ GIANTS Kornwestheim<\/strong>, sowie die BG Tamm\/Bietigheim und die BG Remseck f\u00fcr das Final-Four um die Meisterschaft qualifiziert. Im ersten Spiel standen sich die HAKRO Merlins Crailsheim und die BG Remseck gegen\u00fcber. Remseck war gegen die Crailsheimer zwar der Underdog, sorgte aber f\u00fcr eine faustdicke \u00dcberraschung und gewann gegen die Merlins nach einem hart umk\u00e4mpften Spiel mit 65:62 (17:16, 42:30, 49.46). In der zweiten Partie mussten die Giants gegen die BG Tamm\/Bietigheim antreten. In den Liga Partien, konnten beide Teams ihre Heimspiele gewinnen. Es war also Spannung angesagt. Die Giants, die eine starke Saison gespielt hatten und nur drei Niederlagen einstecken mussten, waren darauf fokussiert, das Endspiel zu erreichen. Das Spiel begann zun\u00e4chst verhalten, mit Vorteilen f\u00fcr die BG die nach dem ersten Viertel mit 11:17 in F\u00fchrung lag. Im zweien Viertel zeigten dann die Giants ihr wahre Gesicht und machten das Spiel. Aus dem R\u00fcckstand wurde eine 32:25 F\u00fchrung zur Halbzeit. Im dritten Viertel war es dann wieder Tamm\/Bietigheim die mehr vom Spiel hatten und das Viertel mit 14:18 f\u00fcr sich entschied. Somit lagen die Giants nur noch knapp mit 46:43 in F\u00fchrung. Dass die Giants unbedingt ins Finale wollten, machten sie im Schlussviertel deutlich. Sie \u00fcbernahmen wieder das Kommando und \u00fcberzeugten mit einer starken Offensive. Mit einem 66:49 Sieg zogen sie dann auch ins Finale ein. Im Spiel um Platz drei standen sich somit die HAKRO Merlins Crailsheim und die BG Tamm\/Bie-tigheim gegen\u00fcber, das die Merlins mit 82:53 ( 21:11, 48:26, 58:43) gewannen. Das Endspiel lautet also SZ Giants Kornwestheim gegen die BG Remseck. Es war eine harte Nuss, die es f\u00fcr die Giants zu knacken galt. In der zun\u00e4chst recht offensiv gef\u00fchrten Partie waren die Giants im ersten Viertel das besser agierende Team und gingen mit 21:17 in F\u00fchrung. Das zweite Viertel geh\u00f6rte dann mit 16:13 der BG Remseck. Zur Halbzeit lagen die Giants somit nur noch knapp mit 34:33 in F\u00fchrung. Nach dem Seitenwechsel verflachte etwas die Partie. Beide Teams setzten verst\u00e4rkt auf ihre Defensive. W\u00e4hrend den Remsecker nur 8 Punkte gelangen, erzielten die Giants 13 Punkte und hatten beim Stande von 47:41 ein d\u00fcnnes Polster von sechs Punkten. Das Schlussviertel verlief dann ganz im Sinne der Giants. Die Defensive hielt die BG weiter in Schach und die Offensive profitierte aus den Balleroberungen. Offenbar fehlte den Remseckern die Kraft, um noch mithalten zu k\u00f6nnen. Am Ende bejubelten die Giants mit einem deutlichen 70:56 Sieg die Landesliga-Meisterschaft.<br \/>Es spielten: Ralfs Baranovskis, Luke Conrad, Sam Conrad, Roan Filip Gec, Jaydan Kenserski, Louis Kretz, Henning L\u00fctters, Luan Mader, Semin Mesanovic, Konstantin Selcho, Julius Waibel und Oliver Zeitz.<\/p>\n<p>Die <strong>weibliche U 14<\/strong> hatte sich als Tabellenf\u00fchrer der Bezirksliga 1 f\u00fcr das Final-Four um die Bezirksliga Meisterschaft qualifiziert. Mit dabei der Tabellenzweite, Steinen-bronn Beasts, sowie aus der Bezirksliga 2 als Tabellenf\u00fchrer die Steinenbronn Mini Beasts und der BBC Stuttgart. Im ersten Duell standen sich die beiden Steinen-bronner Beast gegen\u00fcber, dass die Beasts gegen ihre Minis mit 45:33 (13:3, 24:18, 35:28) gewannen und somit ins Endspiel einzogen. Im zweiten Spiel standen sich dann die Kornwestheimer M\u00e4dchen und der BBC Stuttgart gegen\u00fcber. \u00a0Die Kornwestheimerinnen, die eine starke Hauptrunde gespielt haben und nur eine Niederlage kassierten, fanden gegen die BBC M\u00e4dchen nicht zu ihrem Spiel. Nach einem 6:14 R\u00fcckstand nach dem ersten Viertel, lagen sie zur Halbzeit bereits mit 16:32 zur\u00fcck. Das besserte sich auch nicht nach dem Seitenwechsel. Die BBC M\u00e4dchen bestimmten weiter das Spielgeschehen und zogen im dritten Viertel auf 26:46 davon. Zwar zeigten die Giants im Schlussviertel Kampfgeist, doch es reichte nicht, das Spiel zu drehen und mussten sich mit 42:59 geschlagen geben. Somit spielten sie gegen die Steinenbronn Mini Beasts um Platz drei. Nach der vorherigen Niederlage, war offenbar die Entt\u00e4uschung gro\u00df und der Kampfgeist gebrochen, denn sie \u00fcberlie\u00dfen den Mini Beasts das Spiel. Und die nutzten ihre Chancen konsequent. Mit 96:48 (19:14, 39:22, 66:39) fertigten sie die Giants ab, die nun als Vierter der Bezirksliga die Saison beschlie\u00dfen. Meister wurden die Steinenbronn Beasts, die den BBC Stuttgart mit 62:42 (10:9,\u00a0 31:18, 44:28) besiegten.\u00a0\u00a0\u00a0<br \/>Es spielten: Dalia Bsul, Leni Buchen, Sena Refika Bulut, Sarah Cseszka, Zaynah Ibrahim, Lena Kaiser, Greta Mantel, Celina Pillich Acosta, Belinav Poyraz, Anna Schoch , Erika Obianuju Udeh und Ljubica Zivkovic.<\/p>\n<p><strong>In der Jugend Oberliga feiert die U 18\/1 zun\u00e4chst gegen Kirchheim einen Sieg um am n\u00e4chsten Tag in Kirchheim Federn zu lassen. Auch die U 14\/1 muss sich den Kirchheimern geschlagen geben.<\/strong><\/p>\n<p>Einen weiteren Doppelspieltag in der Jugend Oberliga hatte die <strong>U 18\/1<\/strong> der SZ Giants Kornwestheim. Am Samstag empfingen die Giants den VfL Kirchheim und am Sonntag mussten sie dann in Kirchheim antreten. Gegen den VfL war ein Heimsieg das Ziel, denn zum Saisonschluss am kommenden Wochenende, will man im letzten Heimspiel die Rote Laterne als Schlusslicht abgeben. Ein erster Schritt wurde gemacht, denn die Giants gewannen gegen den VfL Kirchheim mit 85:71. Nach einem offensiven ersten Viertel lagen die Giants mit 29:23 in F\u00fchrung. Kirchheim verst\u00e4rkte im zweiten Viertel seine Defensivarbeit, so dass sich die Offensivkr\u00e4fte der Giants schwertaten, erfolgreich zum Abschluss zu kommen. Ander die G\u00e4ste, die das Viertel mit 13:22 f\u00fcr sich entschieden. Dadurch lagen die Giants beim Seitenwechsel nur noch mit einem Punkt, 44:43 in F\u00fchrung. In der zweiten Halbzeit setzten beide Teams weiter auf die Offensive. Nun machten auch die Giants wieder die Punkte und entschieden das dritte Viertel mit 22:20 wieder f\u00fcr sich. Ins Schlussviertel ging es mit einer 66:63 F\u00fchrung f\u00fcr die Giants, denen es nun gelang, die Kirchheimer Angriffe erfolgreich zu unterbinden und aus den Ballgewinnen Kapital zu schlagen. Nur noch 8 Punkte erzielten die G\u00e4ste, die mit einer 85:71 Niederlage nach Hause geschickt wurden. \u00a0<br \/>Am Sonntag ging dann das R\u00fcckspiel in Kirchheim \u00fcber die B\u00fchne. Wer gehofft hatte, dass die Giants den Schwung und Elan vom Vortag mitnehmen und mit einem weiteren Sieg den Sprung vom Tabellenende schaffen, der sah sich get\u00e4uscht. In keiner Phase des Spiels konnten die Giants gegen die stark auftretenden Kirch-heimer mithalten. Nach dem ersten Viertel lagen die Giants mit 23:15 \u201enur\u201c mit acht Punkten im R\u00fcckstand. Aber anstelle sich dagegen zu stemmen, bekamen die Giants Kirchheim weiterhin nicht in den Griff und lagen zur Halbzeit mit 51:25 schon recht deutlich im R\u00fcckstand. Im dritten Viertel wurde das Angriffsspiel der Giants dann wieder etwas besser, doch die Defensive bot nach wie vor zu viele L\u00fccken, die die Gastgeber erfolgreich ausnutzten. Zu Beginn des Schlussviertels lagen die Giants aussichtslos mit 76:42 im R\u00fcckstand, so dass letztendlich der deutliche 85:55 Sieg der Kirchheimer nur noch zur reinen Formsache wurde. Damit bleiben die Giants Schlusslicht in der Tabelle, haben aber im kommenden Heimspiel die Gelegenheit gegen den BBC Stuttgart, mit einem Sieg den Stuttgartern die Rote Laterne zu \u00fcbergeben.<br \/>Es spielten: Kaon Biraj (6\/2), Sven Aurel Delic (-\/2), Kilian Goldstein (12\/14), Fabian \u00a0Harre (7\/6), Gino Kouadio (12\/6), Deniz Lepke (19\/13), Shinnosuke Sato (18\/8), Konstantin Selcho und Marvin Selmani (11\/4).<\/p>\n<p>Ebenfalls musste die <strong>U 14\/1<\/strong> der Giants in der Jugend Oberliga zu Hause gegen den VfL Kirchheim antreten. In ihrem vorletzten Spiel in dieser Saison, wollten sich die Giants mit einem Heimsieg von ihren Fans verabschieden. Das Ziel geriet zun\u00e4chst im ersten Viertel in weiter Ferne, denn Kirchheim bestimmte das Spiel geschehen und ging mit 11:21 in F\u00fchrung. Das weckte die Giants, die nun im zweiten Viertel deutlich besser agierten und ihre Chancen in der Offensive nutzten. Allerdings, die Defensive bot immer noch zu viele L\u00fccken. So ging zwar das zweit Viertel mit 21:18 an die Giants, doch Kirchheim lag zur Halbzeit immer noch mit 32:39 in F\u00fchrung. Nach dem Seitenwechsel bestimmt dann die Giants das Spielgeschehen. Die Defensive war nun besser im Bilde und die Offensive nutzte konsequent ihre Chancen. Erneut ging das Viertel mit 23:16 an die Giants, die damit den Ausgleich zum 55:55 schafften. Im Schlussviertel wollten die Giants dann das Spie vollends drehen und den Sieg, doch Kirchheim hatte was dagegen, ging wieder in F\u00fchrung, die hielt dann bis zum Ert\u00f6nen der Schlusssirene. Mit 70:76 mussten sich die Giants geschlagen geben. In der Tabelle stehen die Giants auf dem siebten, dem vorletzten Tabellenplatz. Mit einem Ausw\u00e4rtssieg im letzten Spiel beim MTV Stuttgart, k\u00f6nnten sie allerdings noch einen Platz gut machen und Sechster werden.<br \/>Es spielten: Benil Asani (4), Justus Baumgartner (2), Kerem Cerit (2), Marko Gregovic, Bora Jusofoski, Angelos Katsaounis (10), Majd Mesanovic (4), Qutin Pirwass, Georgije Lav Popovic (12), Kurtay Poyratz, Kian Retzlaf (2) und Dario Secen (34).<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>In der Landesliga der U 18 Teams hatten sich die ersten vier, also die HAKRO Merlins Crailsheim, SZ GIANTS Kornwestheim, sowie die BG Tamm\/Bietigheim und die BG Remseck f\u00fcr das &#8230;<\/p>\n","protected":false},"author":6,"featured_media":7484,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/9238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/comments?post=9238"}],"version-history":[{"count":1,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/9238\/revisions"}],"predecessor-version":[{"id":9239,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/posts\/9238\/revisions\/9239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/media\/7484"}],"wp:attachment":[{"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/media?parent=9238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/categories?post=9238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.skizunft-basketball.de\/index.php\/wp-json\/wp\/v2\/tags?post=9238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}